{"id":1276,"date":"2024-08-10T00:00:00","date_gmt":"2024-08-10T00:00:00","guid":{"rendered":"https:\/\/lanxing.easiwin.com\/?p=1276"},"modified":"2025-01-09T08:26:23","modified_gmt":"2025-01-09T08:26:23","slug":"7-methods-of-applying-glass-beads","status":"publish","type":"post","link":"https:\/\/lanxingco.com\/pt\/7-methods-of-applying-glass-beads\/","title":{"rendered":"Revela\u00e7\u00e3o de 7 m\u00e9todos fascinantes de aplica\u00e7\u00e3o de contas de vidro em marca\u00e7\u00f5es rodovi\u00e1rias"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Porque \u00e9 que as contas de vidro s\u00e3o importantes<\/h2>\n\n\n\n<p>Antes de nos debru\u00e7armos sobre o \"como\", vamos abordar brevemente o \"porqu\u00ea\". <a href=\"https:\/\/en.wikipedia.org\/wiki\/Glass_bead_making\" target=\"_blank\" rel=\"noopener\">Contas de vidro<\/a> s\u00e3o os her\u00f3is desconhecidos da seguran\u00e7a rodovi\u00e1ria, fornecendo retrorreflectividade que torna as marca\u00e7\u00f5es rodovi\u00e1rias vis\u00edveis \u00e0 noite e em m\u00e1s condi\u00e7\u00f5es climat\u00e9ricas. Funcionam reflectindo a luz dos far\u00f3is do ve\u00edculo de volta para o condutor, criando aquele brilho familiar em que todos confiamos para navegar em seguran\u00e7a.<\/p>\n\n\n\n<p>Passemos agora ao assunto principal: Como \u00e9 que as contas de vidro s\u00e3o aplicadas nas tintas ou materiais de marca\u00e7\u00e3o rodovi\u00e1ria?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">7 T\u00e9cnicas deslumbrantes: A arte da aplica\u00e7\u00e3o de missangas<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1. O m\u00e9todo cl\u00e1ssico de polvilhar: M\u00e9todo Drop-On<\/h3>\n\n\n\n<p>Imagine que est\u00e1 a decorar um bolo com granulado. Agora, superdimensione esse bolo para propor\u00e7\u00f5es de estrada, e tem a ideia b\u00e1sica do m\u00e9todo \"drop-on\"!<\/p>\n\n\n\n<p><strong>Como funciona:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>A tinta de marca\u00e7\u00e3o rodovi\u00e1ria ou o material termopl\u00e1stico \u00e9 aplicado na superf\u00edcie da estrada.<\/li>\n\n\n\n<li>Enquanto o material ainda est\u00e1 h\u00famido ou derretido, as contas de vidro s\u00e3o literalmente salpicadas sobre a superf\u00edcie.<\/li>\n\n\n\n<li>As p\u00e9rolas embebem-se parcialmente no material de marca\u00e7\u00e3o.<\/li>\n<\/ol>\n\n\n\n<p><strong>Pr\u00f3s:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Simples e amplamente utilizado<\/li>\n\n\n\n<li>Pode ser facilmente ajustado para diferentes densidades de p\u00e9rolas<\/li>\n<\/ul>\n\n\n\n<p><strong>Contras:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Algumas p\u00e9rolas podem n\u00e3o ser incorporadas corretamente<\/li>\n\n\n\n<li>Pode ser afetado pelo vento durante a aplica\u00e7\u00e3o<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">2. A t\u00e9cnica de sandu\u00edche: Pr\u00e9-mistura + Drop-On<\/h3>\n\n\n\n<p>Porqu\u00ea contentar-se com uma camada quando pode ter duas? A t\u00e9cnica da sandu\u00edche combina o melhor dos dois mundos.<\/p>\n\n\n\n<p><strong>Como funciona:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>As contas de vidro s\u00e3o misturadas na <a href=\"https:\/\/lanxingco.com\/pt\/product-category\/road-marking-glass-beads\/\">material de marca\u00e7\u00e3o rodovi\u00e1ria <\/a>antes da aplica\u00e7\u00e3o (pr\u00e9-mistura).<\/li>\n\n\n\n<li>O material pr\u00e9-misturado \u00e9 aplicado na superf\u00edcie da estrada.<\/li>\n\n\n\n<li>As p\u00e9rolas adicionais s\u00e3o polvilhadas por cima enquanto o material ainda est\u00e1 h\u00famido (drop-on).<\/li>\n<\/ol>\n\n\n\n<p><strong>Pr\u00f3s:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proporciona uma retrorreflectividade imediata e a longo prazo<\/li>\n\n\n\n<li>Assegura a presen\u00e7a de p\u00e9rolas mesmo quando a marca\u00e7\u00e3o se desgasta<\/li>\n<\/ul>\n\n\n\n<p><strong>Contras:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Processo de candidatura mais complexo<\/li>\n\n\n\n<li>Custos de material mais elevados<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">3. O mergulho profundo: M\u00e9todo de inje\u00e7\u00e3o<\/h3>\n\n\n\n<p>Para aqueles momentos em que o n\u00edvel superficial n\u00e3o \u00e9 suficiente, mergulhamos fundo com o m\u00e9todo de inje\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Como funciona:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>O <a href=\"https:\/\/lanxingco.com\/pt\/product-category\/road-marking-glass-beads\/\">material de marca\u00e7\u00e3o rodovi\u00e1ria <\/a>\u00e9 aplicado \u00e0 superf\u00edcie.<\/li>\n\n\n\n<li>As esferas de vidro s\u00e3o injectadas \u00e0 for\u00e7a no material h\u00famido utilizando ar pressurizado.<\/li>\n\n\n\n<li>Isto garante uma incorpora\u00e7\u00e3o mais profunda e uniforme das p\u00e9rolas.<\/li>\n<\/ol>\n\n\n\n<p><strong>Pr\u00f3s:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Excelente reten\u00e7\u00e3o de p\u00e9rolas<\/li>\n\n\n\n<li>Distribui\u00e7\u00e3o uniforme das p\u00e9rolas<\/li>\n<\/ul>\n\n\n\n<p><strong>Contras:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Requer equipamento especializado<\/li>\n\n\n\n<li>Pode ser mais moroso<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">4. A panela de press\u00e3o: Termoformagem<\/h3>\n\n\n\n<p>Quando o calor est\u00e1 a aumentar, a termoformagem est\u00e1 \u00e0 altura da ocasi\u00e3o.<\/p>\n\n\n\n<p><strong>Como funciona:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>As esferas de vidro s\u00e3o misturadas num material termopl\u00e1stico de marca\u00e7\u00e3o rodovi\u00e1ria.<\/li>\n\n\n\n<li>A mistura \u00e9 aquecida at\u00e9 ficar fundida.<\/li>\n\n\n\n<li>O material fundido \u00e9 extrudido para a superf\u00edcie da estrada, com gr\u00e2nulos distribu\u00eddos por todo o lado.<\/li>\n<\/ol>\n\n\n\n<p><strong>Pr\u00f3s:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Marca\u00e7\u00f5es muito duradouras<\/li>\n\n\n\n<li>Excelente distribui\u00e7\u00e3o das p\u00e9rolas<\/li>\n<\/ul>\n\n\n\n<p><strong>Contras:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Requer equipamento especializado<\/li>\n\n\n\n<li>Custos iniciais mais elevados<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">5. O trabalho de pintura: Aplica\u00e7\u00e3o de tinta pr\u00e9-misturada<\/h3>\n\n\n\n<p>Por vezes, as solu\u00e7\u00f5es mais simples s\u00e3o as melhores. A aplica\u00e7\u00e3o de tinta pr\u00e9-misturada \u00e9 uma delas.<\/p>\n\n\n\n<p><strong>Como funciona:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>As esferas de vidro s\u00e3o misturadas diretamente na tinta de marca\u00e7\u00e3o rodovi\u00e1ria.<\/li>\n\n\n\n<li>A tinta pr\u00e9-misturada \u00e9 aplicada \u00e0 superf\u00edcie da estrada utilizando equipamento de pintura normal.<\/li>\n<\/ol>\n\n\n\n<p><strong>Pr\u00f3s:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Processo de candidatura simples<\/li>\n\n\n\n<li>Distribui\u00e7\u00e3o consistente das p\u00e9rolas<\/li>\n<\/ul>\n\n\n\n<p><strong>Contras:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Limitado a marca\u00e7\u00f5es \u00e0 base de tinta<\/li>\n\n\n\n<li>Pode ter uma menor retrorreflectividade inicial em compara\u00e7\u00e3o com os m\u00e9todos de gota a gota<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">6. O duplo golpe: dupla aplica\u00e7\u00e3o<\/h3>\n\n\n\n<p>Para aqueles que acreditam que dois \u00e9 sempre melhor do que um, o m\u00e9todo de aplica\u00e7\u00e3o dupla n\u00e3o desilude.<\/p>\n\n\n\n<p><strong>Como funciona:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u00c9 aplicada uma camada de base de material de marca\u00e7\u00e3o rodovi\u00e1ria (com ou sem p\u00e9rolas pr\u00e9-misturadas).<\/li>\n\n\n\n<li>Uma segunda camada de material, mais fina, \u00e9 imediatamente aplicada por cima.<\/li>\n\n\n\n<li>As contas de vidro s\u00e3o colocadas na camada superior fresca.<\/li>\n<\/ol>\n\n\n\n<p><strong>Pr\u00f3s:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Excelente reten\u00e7\u00e3o de p\u00e9rolas<\/li>\n\n\n\n<li>Durabilidade superior<\/li>\n<\/ul>\n\n\n\n<p><strong>Contras:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mais demorado<\/li>\n\n\n\n<li>Custos de material mais elevados<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">7. A abordagem de alta tecnologia: Distribuidores de esferas automatizados<\/h3>\n\n\n\n<p>Bem-vindo ao futuro da marca\u00e7\u00e3o rodovi\u00e1ria! Os distribuidores autom\u00e1ticos de p\u00e9rolas est\u00e3o a mudar o jogo.<\/p>\n\n\n\n<p><strong>Como funciona:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>O material de marca\u00e7\u00e3o de estradas \u00e9 aplicado utilizando um cami\u00e3o ou uma m\u00e1quina especializada.<\/li>\n\n\n\n<li>Um sistema automatizado distribui p\u00e9rolas de vidro a uma velocidade e padr\u00e3o controlados.<\/li>\n\n\n\n<li>Alguns sistemas podem ajustar a aplica\u00e7\u00e3o do tal\u00e3o com base na velocidade do ve\u00edculo e noutros factores.<\/li>\n<\/ol>\n\n\n\n<p><strong>Pr\u00f3s:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aplica\u00e7\u00e3o altamente precisa e consistente<\/li>\n\n\n\n<li>Pode adaptar-se a condi\u00e7\u00f5es vari\u00e1veis em tempo real<\/li>\n<\/ul>\n\n\n\n<p><strong>Contras:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Equipamento dispendioso<\/li>\n\n\n\n<li>Requer forma\u00e7\u00e3o especializada para funcionar<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O confronto da aplica\u00e7\u00e3o de p\u00e9rolas: Um olhar comparativo<\/h2>\n\n\n\n<p>Agora que j\u00e1 explor\u00e1mos estas t\u00e9cnicas deslumbrantes, vamos p\u00f4-las frente a frente numa compara\u00e7\u00e3o amig\u00e1vel:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>M\u00e9todo<\/th><th>Facilidade de aplica\u00e7\u00e3o<\/th><th>Durabilidade<\/th><th>Retrorreflectividade inicial<\/th><th>Custo<\/th><\/tr><\/thead><tbody><tr><td>Drop-On<\/td><td>\u2605\u2605\u2605\u2605\u2606<\/td><td>\u2605\u2605\u2606\u2606\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2605<\/td><td>$<\/td><\/tr><tr><td>Sandu\u00edche<\/td><td>\u2605\u2605\u2605\u2606\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2606<\/td><td>$$<\/td><\/tr><tr><td>Inje\u00e7\u00e3o<\/td><td>\u2605\u2605\u2606\u2606\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2605<\/td><td>\u2605\u2605\u2605\u2606\u2606<\/td><td>$$$<\/td><\/tr><tr><td>Termoformagem<\/td><td>\u2605\u2605\u2606\u2606\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2605<\/td><td>\u2605\u2605\u2605\u2606\u2606<\/td><td>$$$$<\/td><\/tr><tr><td>Tinta pr\u00e9-misturada<\/td><td>\u2605\u2605\u2605\u2605\u2605<\/td><td>\u2605\u2605\u2606\u2606\u2606<\/td><td>\u2605\u2605\u2606\u2606\u2606<\/td><td>$<\/td><\/tr><tr><td>Aplica\u00e7\u00e3o dupla<\/td><td>\u2605\u2605\u2606\u2606\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2605<\/td><td>$$$<\/td><\/tr><tr><td>Dispensadores autom\u00e1ticos<\/td><td>\u2605\u2605\u2605\u2606\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2606<\/td><td>\u2605\u2605\u2605\u2605\u2605<\/td><td>$$$$<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">A ci\u00eancia por detr\u00e1s do brilho: Factores que afectam a aplica\u00e7\u00e3o das p\u00e9rolas<\/h2>\n\n\n\n<p>Aplicar contas de vidro nas marca\u00e7\u00f5es rodovi\u00e1rias n\u00e3o \u00e9 apenas polvilhar alguns peda\u00e7os brilhantes em tinta h\u00famida. H\u00e1 toda uma ci\u00eancia por detr\u00e1s disso! V\u00e1rios factores entram em jogo:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Tamanho e grada\u00e7\u00e3o do gr\u00e2nulo<\/h3>\n\n\n\n<p>Nem todas as p\u00e9rolas s\u00e3o iguais. Uma mistura de tamanhos de p\u00e9rolas garante uma \u00f3ptima retrorreflexividade e longevidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Taxa de aplica\u00e7\u00e3o<\/h3>\n\n\n\n<p>Se as p\u00e9rolas forem demasiado pequenas, a marca\u00e7\u00e3o n\u00e3o ser\u00e1 suficientemente reflectora. Se forem demasiadas, est\u00e1 a desperdi\u00e7ar dinheiro (e missangas).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Profundidade de incorpora\u00e7\u00e3o<\/h3>\n\n\n\n<p>Idealmente, as p\u00e9rolas devem ser embutidas cerca de 60% no material de marca\u00e7\u00e3o. Isto garante que est\u00e3o seguras, mas ainda t\u00eam uma superf\u00edcie exposta suficiente para refletir a luz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Viscosidade do material<\/h3>\n\n\n\n<p>O material de marca\u00e7\u00e3o rodovi\u00e1ria tem de ter a consist\u00eancia correta - nem demasiado espesso, nem demasiado fino - para permitir uma incorpora\u00e7\u00e3o adequada das esferas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Condi\u00e7\u00f5es climat\u00e9ricas<\/h3>\n\n\n\n<p>A temperatura, a humidade e o vento podem afetar a aplica\u00e7\u00e3o e a incorpora\u00e7\u00e3o das p\u00e9rolas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Textura da superf\u00edcie da estrada<\/h3>\n\n\n\n<p>Uma superf\u00edcie de estrada mais lisa permite uma distribui\u00e7\u00e3o e incorpora\u00e7\u00e3o mais uniforme dos tal\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Factores que afectam a aplica\u00e7\u00e3o das esferas de vidro<\/h2>\n\n\n\n<p>A efic\u00e1cia da aplica\u00e7\u00e3o de esferas de vidro na marca\u00e7\u00e3o de estradas depende de v\u00e1rios factores-chave, incluindo<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Fator<\/th><th>Descri\u00e7\u00e3o<\/th><th>Impacto no desempenho das p\u00e9rolas<\/th><\/tr><\/thead><tbody><tr><td>Tamanho e grada\u00e7\u00e3o das p\u00e9rolas<\/td><td>O tamanho e a distribui\u00e7\u00e3o do tamanho das esferas de vidro<\/td><td>Afecta a incorpora\u00e7\u00e3o, a retrorreflexividade e a durabilidade<\/td><\/tr><tr><td>Qualidade das p\u00e9rolas<\/td><td>A redondeza, a clareza e o \u00edndice de refra\u00e7\u00e3o das p\u00e9rolas<\/td><td>Influencia a efic\u00e1cia e a consist\u00eancia da reflex\u00e3o da luz<\/td><\/tr><tr><td>Compatibilidade do material de marca\u00e7\u00e3o<\/td><td>A compatibilidade das p\u00e9rolas de vidro com o material de marca\u00e7\u00e3o<\/td><td>Determina a reten\u00e7\u00e3o do cord\u00e3o e o desempenho geral da marca\u00e7\u00e3o<\/td><\/tr><tr><td>Taxa de aplica\u00e7\u00e3o e uniformidade<\/td><td>A quantidade de p\u00e9rolas aplicadas por unidade de superf\u00edcie e a uniformidade da distribui\u00e7\u00e3o<\/td><td>Afecta a retrorreflexividade e a durabilidade da marca\u00e7\u00e3o<\/td><\/tr><tr><td>Condi\u00e7\u00f5es ambientais<\/td><td>Temperatura, humidade e humidade da superf\u00edcie durante a aplica\u00e7\u00e3o<\/td><td>Pode afetar a ades\u00e3o e a incorpora\u00e7\u00e3o do cord\u00e3o<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Ao considerar cuidadosamente e otimizar estes factores, os profissionais de marca\u00e7\u00e3o de estradas podem garantir que as esferas de vidro s\u00e3o aplicadas eficazmente, resultando em marca\u00e7\u00f5es de pavimento de alta qualidade e duradouras que mant\u00eam as nossas estradas seguras e iluminadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tecnologias que melhoram a aplica\u00e7\u00e3o das esferas de vidro<\/strong><\/h2>\n\n\n\n<p>Os avan\u00e7os tecnol\u00f3gicos melhoraram significativamente a aplica\u00e7\u00e3o das esferas de vidro na marca\u00e7\u00e3o rodovi\u00e1ria, conduzindo a um melhor desempenho e efici\u00eancia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Distribuidores autom\u00e1ticos de esferas<\/strong><\/h3>\n\n\n\n<p>Os distribuidores autom\u00e1ticos de p\u00e9rolas ligados \u00e0s m\u00e1quinas de marca\u00e7\u00e3o de estradas asseguram uma distribui\u00e7\u00e3o precisa e uniforme das p\u00e9rolas de vidro. Estes distribuidores podem ser calibrados para controlar o caudal, garantindo uma cobertura consistente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Aquecedores termopl\u00e1sticos por infravermelhos<\/strong><\/h3>\n\n\n\n<p>Os aquecedores de infravermelhos s\u00e3o utilizados no m\u00e9todo do termopl\u00e1stico pr\u00e9-formado para aquecer uniformemente o material, assegurando uma ades\u00e3o e incorpora\u00e7\u00e3o adequadas das p\u00e9rolas. Estes aquecedores fornecem uma fonte de calor controlada, reduzindo o risco de sobreaquecimento ou de aplica\u00e7\u00e3o irregular.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. M\u00e1quinas de marca\u00e7\u00e3o com GPS<\/strong><\/h3>\n\n\n\n<p>As m\u00e1quinas de marca\u00e7\u00e3o rodovi\u00e1ria com GPS podem aplicar marca\u00e7\u00f5es com elevada precis\u00e3o, assegurando a coloca\u00e7\u00e3o exacta do material de marca\u00e7\u00e3o e das esferas de vidro. Esta tecnologia \u00e9 particularmente \u00fatil para tra\u00e7ados rodovi\u00e1rios complexos e zonas de elevado tr\u00e1fego.<\/p>","protected":false},"excerpt":{"rendered":"<p>Existem v\u00e1rios m\u00e9todos de aplica\u00e7\u00e3o de p\u00e9rolas de vidro em tintas ou materiais de marca\u00e7\u00e3o rodovi\u00e1ria.<\/p>","protected":false},"author":3,"featured_media":1271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-1276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-road-marking-glass-beads"],"acf":[],"taxonomy_info":{"category":[{"value":8,"label":"Road Marking Glass Beads"}]},"featured_image_src_large":["https:\/\/lanxingco.com\/wp-content\/uploads\/2024\/07\/images-7.jpg",300,168,false],"author_info":{"display_name":"yiyunyingjiangjiang","author_link":"https:\/\/lanxingco.com\/pt\/author\/yiyunyingjiangjiang\/"},"comment_info":"","category_info":[{"term_id":8,"name":"Road Marking Glass Beads","slug":"road-marking-glass-beads","term_group":0,"term_taxonomy_id":8,"taxonomy":"category","description":"Road Marking Glass Beads manufacturer in China","parent":0,"count":68,"filter":"raw","cat_ID":8,"category_count":68,"category_description":"Road Marking Glass Beads manufacturer in China","cat_name":"Road Marking Glass Beads","category_nicename":"road-marking-glass-beads","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/posts\/1276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/comments?post=1276"}],"version-history":[{"count":3,"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/posts\/1276\/revisions"}],"predecessor-version":[{"id":1840,"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/posts\/1276\/revisions\/1840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/media\/1271"}],"wp:attachment":[{"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/media?parent=1276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/categories?post=1276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanxingco.com\/pt\/wp-json\/wp\/v2\/tags?post=1276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}